{"id":435,"date":"2026-04-30T15:04:12","date_gmt":"2026-04-30T15:04:12","guid":{"rendered":"https:\/\/moroccostarstravel.com\/explore\/"},"modified":"2026-04-30T17:57:06","modified_gmt":"2026-04-30T17:57:06","slug":"tours-from-agadir","status":"publish","type":"mdp_explore_page","link":"https:\/\/moroccostarstravel.com\/de\/tours-from-agadir\/","title":{"rendered":"Touren von Agadir aus"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":[],"class_list":["post-435","mdp_explore_page","type-mdp_explore_page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/moroccostarstravel.com\/de\/wp-json\/wp\/v2\/mdp_explore_page\/435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moroccostarstravel.com\/de\/wp-json\/wp\/v2\/mdp_explore_page"}],"about":[{"href":"https:\/\/moroccostarstravel.com\/de\/wp-json\/wp\/v2\/types\/mdp_explore_page"}],"wp:attachment":[{"href":"https:\/\/moroccostarstravel.com\/de\/wp-json\/wp\/v2\/media?parent=435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}